{"id":4247,"date":"2025-05-22T10:33:30","date_gmt":"2025-05-22T08:33:30","guid":{"rendered":"https:\/\/www.bage-pontdevaux-tourisme.com\/op-een-steenworp-afstand-van-de-bourgogne-een-gastvrij-platteland-tussen-bresse-en-saone\/"},"modified":"2026-05-02T11:37:19","modified_gmt":"2026-05-02T09:37:19","slug":"op-een-steenworp-afstand-van-de-bourgogne-een-gastvrij-platteland-tussen-bresse-en-saone","status":"publish","type":"page","link":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/","title":{"rendered":"Op een steenworp afstand van de Bourgogne, <strong>een gastvrij platteland<\/strong><strong>tussen Bresse en Sa\u00f4ne<\/strong>"},"content":{"rendered":"\n<div class=\"wp-block-ws-library-ws-header-principal is-layout-constrained alignfull\"><div class=\"group-media has-image\"><img fetchpriority=\"high\" decoding=\"sync\" src=\"https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/05\/cac08141b5f198cbe2823a261c55a72060ffda0d-1920x1018.jpg\" alt=\"\" loading=\"eager\" class=\"image_large_square wp-image-4082 \"\/><\/div><div class=\"group-content\"><div class=\"title\"><h1>Op een steenworp afstand van de Bourgogne, <strong>een gastvrij platteland<\/strong><strong>tussen Bresse en Sa\u00f4ne<\/strong><\/h1><\/div><div class=\"introduction\"><p>Begrensd door de <strong>immense weide van de Val de Sa\u00f4ne<\/strong>, waar <strong>uitzonderlijke fauna en flora<\/strong> naast elkaar bestaan, <br\/>dit land van coulisselandschap en licht golvend water, gelegen in de Ain, <br\/>biedt rivier-, <strong>culturele<\/strong> en <strong>gastronomische<\/strong> <strong>activiteiten<\/strong>.<br\/>Mis de <strong>dorpen B\u00e2g\u00e9-le-Ch\u00e2tel<\/strong> en <strong>Pont-de-Vaux<\/strong> niet, trots op hun geschiedenis!<\/p><\/div><\/div><\/div>\n\n<div class=\"wp-block-group alignfull has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-ws-library-ws-title is-style-wave-blue\"><h2>Hoogtepunten en entertainment<\/h2><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Geniet het hele jaar door van <strong>gezellige activiteiten<\/strong> : lokale markten, concerten, tentoonstellingen, shows, wandelingen of dorpsfeesten, deel deze onvergetelijke momenten&#8230;.<\/p>\n\n\n<div class=\"alignfull wp-block-ws-apidae-library-ws-apidae-temps-forts\"><div class=\"simple-template\"><div class=\"list-items list-2-4-4\"><div class=\"item\"><div class=\"card card-apidae card-agenda\"><div class=\"group-top\"><div class=\"group-dates\" role=\"group\" aria-label=\"Data van het evenement\"><div class=\"field-dates  ws-apidae-date-coming\" role=\"group\" aria-label=\"Openingsdatum\"><time datetime=\"2026-07-15\"><span class=\"date-day-name\" aria-label=\"Dag\">Woensdag<\/span> <span class=\"date-day\" aria-label=\"Dag\">15<\/span> <span class=\"date-month\" aria-label=\"Maand\">juli<\/span> <span class=\"date-year\" aria-label=\"Jaar\">2026<\/span><span class=\"date-delimiter\" aria-hidden=\"true\"> om <\/span><time class=\"date-hours\" datetime=\"08:00\" aria-label=\"Openingstijden\">08 h<\/time><\/time><\/div><\/div><\/div><div class=\"group-media\"><div class=\"field-image\"><img decoding=\"async\" src=\"https:\/\/images.weserv.nl\/?url=https:\/\/static.apidae-tourisme.com\/filestore\/objets-touristiques\/images\/203\/119\/19953611-diaporama.jpg&#038;w=320&#038;h=420&#038;fit=cover&#038;output=webp&#038;q=45\" alt=\"Wekelijkse markt\"\/><\/div><\/div><div class=\"group-content\"><div class=\"field-commune\">Pont-de-Vaux<\/div><div class=\"field-title\">Wekelijkse markt<\/div><div class=\"field-description\">Levendig en kleurrijk, je vindt er Bresse gevogelte, fruit en&#8230;<\/div><\/div><div class=\"field-link\"><a href=\"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/fiche\/wekelijkse-markt\/\" class=\"cardlink\">Wekelijkse markt<\/a><\/div><\/div><\/div><div class=\"item\"><div class=\"card card-apidae card-agenda\"><div class=\"group-top\"><div class=\"group-dates\" role=\"group\" aria-label=\"Data van het evenement\"><div class=\"field-dates  ws-apidae-date-coming\" role=\"group\" aria-label=\"Openingsdatum\"><time datetime=\"2026-07-15\"><span class=\"date-day-name\" aria-label=\"Dag\">Woensdag<\/span> <span class=\"date-day\" aria-label=\"Dag\">15<\/span> <span class=\"date-month\" aria-label=\"Maand\">juli<\/span> <span class=\"date-year\" aria-label=\"Jaar\">2026<\/span><span class=\"date-delimiter\" aria-hidden=\"true\"> om <\/span><time class=\"date-hours\" datetime=\"14:00\" aria-label=\"Openingstijden\">14 h<\/time><\/time><\/div><\/div><\/div><div class=\"group-media\"><div class=\"field-image\"><img decoding=\"async\" src=\"https:\/\/images.weserv.nl\/?url=https:\/\/static.apidae-tourisme.com\/filestore\/objets-touristiques\/images\/227\/100\/20473059-diaporama.jpg&#038;w=320&#038;h=420&#038;fit=cover&#038;output=webp&#038;q=45\" alt=\"&#8220;Van Tony tot Chintreuil&#8221; Een schilder aan het begin van het impressionisme\"\/><\/div><\/div><div class=\"group-content\"><div class=\"field-commune\">Pont-de-Vaux<\/div><div class=\"field-title\">&#8220;Van Tony tot Chintreuil&#8221; Een schilder aan het begin van het impressionisme<\/div><div class=\"field-description\">In 2024 viert het impressionisme zijn 150e verjaardag. Het museum&#8230;<\/div><\/div><div class=\"field-link\"><a href=\"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/fiche\/van-tony-tot-chintreuil-een-schilder-aan-het-begin-van-het-impressionisme\/\" class=\"cardlink\">&#8220;Van Tony tot Chintreuil&#8221; Een schilder aan het begin van het impressionisme<\/a><\/div><\/div><\/div><div class=\"item\"><div class=\"card card-apidae card-agenda\"><div class=\"group-top\"><div class=\"group-dates\" role=\"group\" aria-label=\"Data van het evenement\"><div class=\"field-dates  ws-apidae-date-coming\" role=\"group\" aria-label=\"Openingsdatum\"><time datetime=\"2026-07-15\"><span class=\"date-day-name\" aria-label=\"Dag\">Woensdag<\/span> <span class=\"date-day\" aria-label=\"Dag\">15<\/span> <span class=\"date-month\" aria-label=\"Maand\">juli<\/span> <span class=\"date-year\" aria-label=\"Jaar\">2026<\/span><span class=\"date-delimiter\" aria-hidden=\"true\"> om <\/span><time class=\"date-hours\" datetime=\"14:00\" aria-label=\"Openingstijden\">14 h<\/time><\/time><\/div><\/div><\/div><div class=\"group-media\"><div class=\"field-image\"><img decoding=\"async\" src=\"https:\/\/images.weserv.nl\/?url=https:\/\/static.apidae-tourisme.com\/filestore\/objets-touristiques\/images\/192\/50\/39072448-diaporama.jpg&#038;w=320&#038;h=420&#038;fit=cover&#038;output=webp&#038;q=45\" alt=\"Tentoonstelling Art Trop Podes\"\/><\/div><\/div><div class=\"group-content\"><div class=\"field-commune\">Pont-de-Vaux<\/div><div class=\"field-title\">Tentoonstelling Art Trop Podes<\/div><div class=\"field-description\">Schilderijen, tekeningen, foto&#8217;s en beelden van insecten en andere kleine&#8230;<\/div><\/div><div class=\"field-link\"><a href=\"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/fiche\/tentoonstelling-art-trop-podes\/\" class=\"cardlink\">Tentoonstelling Art Trop Podes<\/a><\/div><\/div><\/div><div class=\"item\"><div class=\"card card-apidae card-agenda\"><div class=\"group-top\"><div class=\"group-dates\" role=\"group\" aria-label=\"Data van het evenement\"><div class=\"field-dates  ws-apidae-date-coming\" role=\"group\" aria-label=\"Openingsdatum\"><time datetime=\"2026-07-25\"><span class=\"date-day-name\" aria-label=\"Dag\">Zaterdag<\/span> <span class=\"date-day\" aria-label=\"Dag\">25<\/span> <span class=\"date-month\" aria-label=\"Maand\">juli<\/span> <span class=\"date-year\" aria-label=\"Jaar\">2026<\/span><span class=\"date-delimiter\" aria-hidden=\"true\"> om <\/span><time class=\"date-hours\" datetime=\"11:30\" aria-label=\"Openingstijden\">11 h 30<\/time><\/time><\/div><\/div><\/div><div class=\"group-media\"><div class=\"field-image\"><img decoding=\"async\" src=\"https:\/\/images.weserv.nl\/?url=https:\/\/static.apidae-tourisme.com\/filestore\/objets-touristiques\/images\/103\/4\/8782951-diaporama.jpg&#038;w=320&#038;h=420&#038;fit=cover&#038;output=webp&#038;q=45\" alt=\"Croisi\u00e8re Seille et dunes\"\/><\/div><\/div><div class=\"group-content\"><div class=\"field-commune\">Pont-de-Vaux<\/div><div class=\"field-title\">Croisi\u00e8re Seille et dunes<\/div><\/div><div class=\"field-link\"><a href=\"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/fiche\/croisiere-seille-et-dunes-4\/\" class=\"cardlink\">Croisi\u00e8re Seille et dunes<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n<div class=\"wp-block-ws-library-ws-button has-text-align-center\"><a href=\"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/alle-hoogtepunten\/\" class=\"wp-block-button__link wp-element-button btn\">  Alle hoogtepunten<\/a><\/div>\n<\/div>\n\n<div class=\"wp-block-group alignfull is-style-rose has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-ws-library-ws-columns alignwide has-2-columns are-vertically-aligned-center layout-5050\">\n<div class=\"wp-block-ws-library-ws-column\"><div class=\"wrapper\"><div class=\"alignfull wp-block-ws-apidae-library-evenements\"><div class=\"simple-template\"><div class=\"list-items\"><div class=\"item\"><div class=\"card card-apidae card-events\"><div class=\"group-top\"><div class=\"group-dates\" role=\"group\" aria-label=\"Data van het evenement\"><div class=\"field-dates  ws-apidae-date-coming\" role=\"group\" aria-label=\"Openingsdatum\"><time datetime=\"2026-07-15\"><span class=\"date-day-name\" aria-label=\"Dag\">Woensdag<\/span> <span class=\"date-day\" aria-label=\"Dag\">15<\/span> <span class=\"date-month\" aria-label=\"Maand\">juli<\/span> <span class=\"date-year\" aria-label=\"Jaar\">2026<\/span><span class=\"date-delimiter\" aria-hidden=\"true\"> om <\/span><time class=\"date-hours\" datetime=\"14:00\" aria-label=\"Openingstijden\">14 h<\/time><\/time><\/div><\/div><\/div><div class=\"group-media\"><\/div><div class=\"group-content\"><div class=\"field-commune\">Pont-de-Vaux<\/div><div class=\"field-title\">Tentoonstelling Art Trop Podes<\/div><div class=\"field-description\">Schilderijen, tekeningen, foto&#8217;s en beelden van insecten en andere kleine&#8230;<\/div><\/div><div class=\"field-link\"><a href=\"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/fiche\/tentoonstelling-art-trop-podes\/\" class=\"cardlink\">Tentoonstelling Art Trop Podes<\/a><\/div><\/div><\/div><div class=\"item\"><div class=\"card card-apidae card-events\"><div class=\"group-top\"><div class=\"group-dates\" role=\"group\" aria-label=\"Data van het evenement\"><div class=\"field-dates  ws-apidae-date-coming\" role=\"group\" aria-label=\"Openingsdatum\"><time datetime=\"2026-07-15\"><span class=\"date-day-name\" aria-label=\"Dag\">Woensdag<\/span> <span class=\"date-day\" aria-label=\"Dag\">15<\/span> <span class=\"date-month\" aria-label=\"Maand\">juli<\/span> <span class=\"date-year\" aria-label=\"Jaar\">2026<\/span><span class=\"date-delimiter\" aria-hidden=\"true\"> om <\/span><time class=\"date-hours\" datetime=\"14:00\" aria-label=\"Openingstijden\">14 h<\/time><\/time><\/div><\/div><\/div><div class=\"group-media\"><\/div><div class=\"group-content\"><div class=\"field-commune\">Pont-de-Vaux<\/div><div class=\"field-title\">&#8220;Van Tony tot Chintreuil&#8221; Een schilder aan het begin van het impressionisme<\/div><div class=\"field-description\">In 2024 viert het impressionisme zijn 150e verjaardag. Het museum&#8230;<\/div><\/div><div class=\"field-link\"><a href=\"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/fiche\/van-tony-tot-chintreuil-een-schilder-aan-het-begin-van-het-impressionisme\/\" class=\"cardlink\">&#8220;Van Tony tot Chintreuil&#8221; Een schilder aan het begin van het impressionisme<\/a><\/div><\/div><\/div><div class=\"item\"><div class=\"card card-apidae card-events\"><div class=\"group-top\"><div class=\"group-dates\" role=\"group\" aria-label=\"Data van het evenement\"><div class=\"field-dates  ws-apidae-date-coming\" role=\"group\" aria-label=\"Openingsdatum\"><time datetime=\"2026-07-15\"><span class=\"date-day-name\" aria-label=\"Dag\">Woensdag<\/span> <span class=\"date-day\" aria-label=\"Dag\">15<\/span> <span class=\"date-month\" aria-label=\"Maand\">juli<\/span> <span class=\"date-year\" aria-label=\"Jaar\">2026<\/span><span class=\"date-delimiter\" aria-hidden=\"true\"> om <\/span><time class=\"date-hours\" datetime=\"08:00\" aria-label=\"Openingstijden\">08 h<\/time><\/time><\/div><\/div><\/div><div class=\"group-media\"><\/div><div class=\"group-content\"><div class=\"field-commune\">Pont-de-Vaux<\/div><div class=\"field-title\">Wekelijkse markt<\/div><div class=\"field-description\">Levendig en kleurrijk, je vindt er Bresse gevogelte, fruit en&#8230;<\/div><\/div><div class=\"field-link\"><a href=\"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/fiche\/wekelijkse-markt\/\" class=\"cardlink\">Wekelijkse markt<\/a><\/div><\/div><\/div><\/div><\/div><div class=\"filters-link\"><a id=\"btn_week\" class=\"wp-element-button btn filter-link link-week\" href=\"https:\/\/www.bage-pontdevaux-tourisme.com\/tous-les-evenements\/?_dates=2026-07-13%2C2026-07-19\">Deze week<\/a><a id=\"btn_month\" class=\"wp-element-button btn filter-link link-month\" href=\"https:\/\/www.bage-pontdevaux-tourisme.com\/tous-les-evenements\/?_dates=2026-07-01%2C2026-07-31\">Deze maand<\/a><\/div><\/div>\n\n\n<div class=\"wp-block-ws-library-ws-button has-text-align-center\"><a href=\"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/alle-evenementen\/\" class=\"wp-block-button__link wp-element-button btn\">  Alle agenda&#8217;s<\/a><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-ws-library-ws-column\"><div class=\"wrapper\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"647\" height=\"685\" src=\"https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/05\/map-ain-5-1.png\" alt=\"\" class=\"wp-image-4089\" srcset=\"https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/05\/map-ain-5-1.png 647w, https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/05\/map-ain-5-1-283x300.png 283w, https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/05\/map-ain-5-1-434x460.png 434w, https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/05\/map-ain-5-1-604x640.png 604w\" sizes=\"auto, (max-width: 647px) 100vw, 647px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-ws-library-ws-button has-text-align-center\"><a href=\"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/verken-de-kaart\/\" class=\"wp-block-button__link wp-element-button btn\">  Verken de kaart!<\/a><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-group alignfull is-style-green has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-ws-library-ws-title is-style-wave-blue\"><h2>Wij (zijn) ge\u00efnspireerd<\/h2><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><br\/>Hier, in Bresse et Sa\u00f4ne, ademen we, doen we onze batterijen op, vinden we onszelf&#8230; Laat u met familie of vrienden verrassen door de <strong>gevarieerde vrijetijdsactiviteiten<\/strong>, de geheimen van het <strong>lokale erfgoed<\/strong> en de <strong>zoetheid van het leven<\/strong> in dit gebied!<\/p>\n\n\n\n<div class=\"wp-block-group alignwide has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group alignwide has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\"><div class=\"alignwide wp-block-ws-library-ws-list-content\"><div class=\"list-items\"><div class=\"item\"><div class=\"card \"><div class=\"group-media\"><div class=\"field-image\"><img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"220\" src=\"https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/01\/image-pour-on-sinspire-320-x-220-px.png\" class=\"attachment-320x220 size-320x220 wp-post-image\" alt=\"\" srcset=\"https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/01\/image-pour-on-sinspire-320-x-220-px.png 320w, https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/01\/image-pour-on-sinspire-320-x-220-px-300x206.png 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/div><\/div><div class=\"group-content\"><div class=\"field-title\">Activiteitenprogramma<\/div><div class=\"field-description\">We hebben een agenda met activiteiten voor de maand juli&#8230;<\/div><\/div><div class=\"field-link\"><a href=\"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/om-je-vakantie-te-vullen\/\" class=\"cardlink\">Activiteitenprogramma<\/a><\/div><\/div><\/div><div class=\"item\"><div class=\"card \"><div class=\"group-media\"><div class=\"field-image\"><img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"220\" src=\"https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/05\/cropped-logo-pays-de-bage-and-pont-de-vauxsvg-320x220.png\" class=\"attachment-320x220 size-320x220\" alt=\"\" \/><\/div><\/div><div class=\"group-content\"><div class=\"field-title\">Spring break-programma<\/div><div class=\"field-description\">We hebben een speciale &#8220;Spring Break&#8221;-entertainmentagenda voor je samengesteld! Iets&#8230;<\/div><\/div><div class=\"field-link\"><a href=\"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/16027\/\" class=\"cardlink\">Spring break-programma<\/a><\/div><\/div><\/div><div class=\"item\"><div class=\"card \"><div class=\"group-media\"><div class=\"field-image\"><img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"220\" src=\"https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/11\/saint-valentin-2024-1-320x220.png\" class=\"attachment-320x220 size-320x220 wp-post-image\" alt=\"\" \/><\/div><\/div><div class=\"group-content\"><div class=\"field-title\">Fijne Valentijnsdag allemaal!<\/div><div class=\"field-description\">Het Toeristenbureau van Pays de Bag\u00e9 en Pont-de-Vaux publiceert een&#8230;<\/div><\/div><div class=\"field-link\"><a href=\"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/het-is-kerstmis\/\" class=\"cardlink\">Fijne Valentijnsdag allemaal!<\/a><\/div><\/div><\/div><div class=\"item\"><div class=\"card \"><div class=\"group-media\"><div class=\"field-image\"><img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"220\" src=\"https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/06\/eleve-visio-jeu-de-piste-1-320x220.jpg\" class=\"attachment-320x220 size-320x220 wp-post-image\" alt=\"\" \/><\/div><\/div><div class=\"group-content\"><div class=\"field-title\">De zomer is hier&#8230;<\/div><div class=\"field-description\">Geniet van avonturen en de natuur door onze gevoelige natuurgebieden&#8230;<\/div><\/div><div class=\"field-link\"><a href=\"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/buiten-en-avontuur\/\" class=\"cardlink\">De zomer is hier&#8230;<\/a><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-ws-library-ws-button has-text-align-center\"><a href=\"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/ervaringen\/\" class=\"wp-block-button__link wp-element-button btn\">  Alle ervaringen<\/a><\/div>\n<\/div>\n\n<div class=\"wp-block-group alignfull has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-ws-library-ws-title is-style-wave-blue\"><h2>Momenten om te delen<\/h2><\/div>\n\n\n\n<p class=\"text-socialwall wp-block-paragraph\">Volg via onze publicaties het nieuws en de ervaringen om in het Pays de Bag\u00e9 en Pont-de-Vaux in foto&#8217;s te wonen!<\/p>\n\n\n\n<div class=\"wp-block-ws-library-ws-socialwall\"><div data-selection=\"1988613\" id=\"ws-socialwall\" data-design=\"29\">Het laden van de sociale muur &#8230;<\/div><script src=\"https:\/\/social-wall.websenso.com\/socialwall3.0.js\" defer><\/script><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Geniet het hele jaar door van gezellige activiteiten : lokale markten, concerten, tentoonstellingen, shows, wandelingen of dorpsfeesten, deel deze onvergetelijke [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4247","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Op een steenworp afstand van de Bourgogne, een gastvrij plattelandtussen Bresse en Sa\u00f4ne - Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Op een steenworp afstand van de Bourgogne, een gastvrij plattelandtussen Bresse en Sa\u00f4ne - Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux\" \/>\n<meta property=\"og:description\" content=\"Geniet het hele jaar door van gezellige activiteiten : lokale markten, concerten, tentoonstellingen, shows, wandelingen of dorpsfeesten, deel deze onvergetelijke [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/\" \/>\n<meta property=\"og:site_name\" content=\"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-02T09:37:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/05\/cac08141b5f198cbe2823a261c55a72060ffda0d-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1234\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/\",\"url\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/\",\"name\":\"Op een steenworp afstand van de Bourgogne, een gastvrij plattelandtussen Bresse en Sa\u00f4ne - Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cac08141b5f198cbe2823a261c55a72060ffda0d-1920x1018.jpg\",\"datePublished\":\"2025-05-22T08:33:30+00:00\",\"dateModified\":\"2026-05-02T09:37:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cac08141b5f198cbe2823a261c55a72060ffda0d-1920x1018.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cac08141b5f198cbe2823a261c55a72060ffda0d-1920x1018.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/op-een-steenworp-afstand-van-de-bourgogne-een-gastvrij-platteland-tussen-bresse-en-saone\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Op een steenworp afstand van de Bourgogne, een gastvrij plattelandtussen Bresse en Sa\u00f4ne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/\",\"name\":\"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/#organization\",\"name\":\"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux\",\"url\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-pays-de-bage-and-pont-de-vaux.svg\",\"contentUrl\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-pays-de-bage-and-pont-de-vaux.svg\",\"caption\":\"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Op een steenworp afstand van de Bourgogne, een gastvrij plattelandtussen Bresse en Sa\u00f4ne - Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/","og_locale":"nl_NL","og_type":"article","og_title":"Op een steenworp afstand van de Bourgogne, een gastvrij plattelandtussen Bresse en Sa\u00f4ne - Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux","og_description":"Geniet het hele jaar door van gezellige activiteiten : lokale markten, concerten, tentoonstellingen, shows, wandelingen of dorpsfeesten, deel deze onvergetelijke [&hellip;]","og_url":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/","og_site_name":"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux","article_modified_time":"2026-05-02T09:37:19+00:00","og_image":[{"width":2560,"height":1234,"url":"https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/05\/cac08141b5f198cbe2823a261c55a72060ffda0d-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/","url":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/","name":"Op een steenworp afstand van de Bourgogne, een gastvrij plattelandtussen Bresse en Sa\u00f4ne - Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux","isPartOf":{"@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/#primaryimage"},"image":{"@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/05\/cac08141b5f198cbe2823a261c55a72060ffda0d-1920x1018.jpg","datePublished":"2025-05-22T08:33:30+00:00","dateModified":"2026-05-02T09:37:19+00:00","breadcrumb":{"@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/#primaryimage","url":"https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/05\/cac08141b5f198cbe2823a261c55a72060ffda0d-1920x1018.jpg","contentUrl":"https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/05\/cac08141b5f198cbe2823a261c55a72060ffda0d-1920x1018.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/op-een-steenworp-afstand-van-de-bourgogne-een-gastvrij-platteland-tussen-bresse-en-saone\/"},{"@type":"ListItem","position":2,"name":"Op een steenworp afstand van de Bourgogne, een gastvrij plattelandtussen Bresse en Sa\u00f4ne"}]},{"@type":"WebSite","@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/#website","url":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/","name":"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux","description":"","publisher":{"@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/#organization","name":"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux","url":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/05\/logo-pays-de-bage-and-pont-de-vaux.svg","contentUrl":"https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/05\/logo-pays-de-bage-and-pont-de-vaux.svg","caption":"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux"},"image":{"@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/pages\/4247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/comments?post=4247"}],"version-history":[{"count":16,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/pages\/4247\/revisions"}],"predecessor-version":[{"id":16570,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/pages\/4247\/revisions\/16570"}],"wp:attachment":[{"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/media?parent=4247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}