{"id":17930,"date":"2026-06-03T10:40:39","date_gmt":"2026-06-03T08:40:39","guid":{"rendered":"https:\/\/www.bage-pontdevaux-tourisme.com\/fiche\/la-ripalonga-3\/"},"modified":"2026-06-03T10:40:39","modified_gmt":"2026-06-03T08:40:39","slug":"la-ripalonga-3","status":"publish","type":"apidae","link":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/fiche\/la-ripalonga-3\/","title":{"rendered":"La Ripalonga"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"idApidae":"5723596"},"apidae-selections":[2400],"apidae-environnements":[],"apidae-chaines":[],"apidae-communes":[641],"apidae-modes_paiement":[17,818,23],"apidae-services":[209],"apidae-langues_parlees":[38],"apidae-equipements":[62,821,824,149,1250,113,71,455,659,128],"apidae-conforts":[308,272,836,1259,1244,302,842,554],"apidae-activites":[],"apidae-tourismes_adaptes":[],"apidae-typologies_promo_sitra":[],"apidae-types_clientele":[],"apidae-types_patrimoine_culturel":[],"apidae-types_commerce_service":[],"apidae-activites_sportives":[],"apidae-commerce_type_detaille":[],"apidae-fete_manifestation_cat":[],"apidae-criteres_internes":[],"apidae-territoires":[419,428,422,434,416,431,440,437],"apidae-salles_equipees_pour":[],"apidae-salles_equipement":[],"apidae-salles_hebergement":[],"apidae-salles_restauration":[],"apidae-categories":[],"apidae-specialites":[],"apidae-indications_periode":[404,410,614,407],"apidae-types_label":[],"apidae-hotel_classement":[638],"apidae-types_hebergement":[2157],"apidae-tourisme_affaire":[1718],"class_list":["post-17930","apidae","type-apidae","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Ripalonga - Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/fiche\/la-ripalonga-3\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Ripalonga - Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/fiche\/la-ripalonga-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/fiche\\\/la-ripalonga-3\\\/\",\"url\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/fiche\\\/la-ripalonga-3\\\/\",\"name\":\"La Ripalonga - Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/#website\"},\"datePublished\":\"2026-06-03T08:40:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/fiche\\\/la-ripalonga-3\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/fiche\\\/la-ripalonga-3\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/fiche\\\/la-ripalonga-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/op-een-steenworp-afstand-van-de-bourgogne-een-gastvrij-platteland-tussen-bresse-en-saone\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Ripalonga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/\",\"name\":\"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/#organization\",\"name\":\"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux\",\"url\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-pays-de-bage-and-pont-de-vaux.svg\",\"contentUrl\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-pays-de-bage-and-pont-de-vaux.svg\",\"caption\":\"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Ripalonga - Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/fiche\/la-ripalonga-3\/","og_locale":"nl_NL","og_type":"article","og_title":"La Ripalonga - Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux","og_url":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/fiche\/la-ripalonga-3\/","og_site_name":"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/fiche\/la-ripalonga-3\/","url":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/fiche\/la-ripalonga-3\/","name":"La Ripalonga - Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux","isPartOf":{"@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/#website"},"datePublished":"2026-06-03T08:40:39+00:00","breadcrumb":{"@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/fiche\/la-ripalonga-3\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/fiche\/la-ripalonga-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/fiche\/la-ripalonga-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/op-een-steenworp-afstand-van-de-bourgogne-een-gastvrij-platteland-tussen-bresse-en-saone\/"},{"@type":"ListItem","position":2,"name":"La Ripalonga"}]},{"@type":"WebSite","@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/#website","url":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/","name":"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux","description":"","publisher":{"@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/#organization","name":"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux","url":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/05\/logo-pays-de-bage-and-pont-de-vaux.svg","contentUrl":"https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/05\/logo-pays-de-bage-and-pont-de-vaux.svg","caption":"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux"},"image":{"@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae\/17930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae"}],"about":[{"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/types\/apidae"}],"wp:attachment":[{"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/media?parent=17930"}],"wp:term":[{"taxonomy":"apidae-selections","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-selections?post=17930"},{"taxonomy":"apidae-environnements","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-environnements?post=17930"},{"taxonomy":"apidae-chaines","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-chaines?post=17930"},{"taxonomy":"apidae-communes","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-communes?post=17930"},{"taxonomy":"apidae-modes_paiement","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-modes_paiement?post=17930"},{"taxonomy":"apidae-services","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-services?post=17930"},{"taxonomy":"apidae-langues_parlees","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-langues_parlees?post=17930"},{"taxonomy":"apidae-equipements","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-equipements?post=17930"},{"taxonomy":"apidae-conforts","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-conforts?post=17930"},{"taxonomy":"apidae-activites","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-activites?post=17930"},{"taxonomy":"apidae-tourismes_adaptes","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-tourismes_adaptes?post=17930"},{"taxonomy":"apidae-typologies_promo_sitra","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-typologies_promo_sitra?post=17930"},{"taxonomy":"apidae-types_clientele","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-types_clientele?post=17930"},{"taxonomy":"apidae-types_patrimoine_culturel","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-types_patrimoine_culturel?post=17930"},{"taxonomy":"apidae-types_commerce_service","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-types_commerce_service?post=17930"},{"taxonomy":"apidae-activites_sportives","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-activites_sportives?post=17930"},{"taxonomy":"apidae-commerce_type_detaille","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-commerce_type_detaille?post=17930"},{"taxonomy":"apidae-fete_manifestation_cat","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-fete_manifestation_cat?post=17930"},{"taxonomy":"apidae-criteres_internes","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-criteres_internes?post=17930"},{"taxonomy":"apidae-territoires","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-territoires?post=17930"},{"taxonomy":"apidae-salles_equipees_pour","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-salles_equipees_pour?post=17930"},{"taxonomy":"apidae-salles_equipement","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-salles_equipement?post=17930"},{"taxonomy":"apidae-salles_hebergement","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-salles_hebergement?post=17930"},{"taxonomy":"apidae-salles_restauration","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-salles_restauration?post=17930"},{"taxonomy":"apidae-categories","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-categories?post=17930"},{"taxonomy":"apidae-specialites","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-specialites?post=17930"},{"taxonomy":"apidae-indications_periode","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-indications_periode?post=17930"},{"taxonomy":"apidae-types_label","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-types_label?post=17930"},{"taxonomy":"apidae-hotel_classement","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-hotel_classement?post=17930"},{"taxonomy":"apidae-types_hebergement","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-types_hebergement?post=17930"},{"taxonomy":"apidae-tourisme_affaire","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/nl\/wp-json\/wp\/v2\/apidae-tourisme_affaire?post=17930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}