{"id":17767,"date":"2026-06-03T10:26:33","date_gmt":"2026-06-03T08:26:33","guid":{"rendered":"https:\/\/www.bage-pontdevaux-tourisme.com\/fiche\/bar-restaurant-le-rodeo-2\/"},"modified":"2026-06-03T10:26:33","modified_gmt":"2026-06-03T08:26:33","slug":"bar-restaurant-le-rodeo-2","status":"publish","type":"apidae","link":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/fiche\/bar-restaurant-le-rodeo-2\/","title":{"rendered":"Bar-Restaurant Le Rod\u00e9o"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"idApidae":"7688798"},"apidae-selections":[2464],"apidae-environnements":[],"apidae-chaines":[],"apidae-communes":[912],"apidae-modes_paiement":[],"apidae-services":[192],"apidae-langues_parlees":[39,42,1338,1233,915],"apidae-equipements":[1026,141,72,75],"apidae-conforts":[],"apidae-activites":[],"apidae-tourismes_adaptes":[1425],"apidae-typologies_promo_sitra":[],"apidae-types_clientele":[],"apidae-types_patrimoine_culturel":[],"apidae-types_commerce_service":[],"apidae-activites_sportives":[],"apidae-commerce_type_detaille":[],"apidae-fete_manifestation_cat":[],"apidae-criteres_internes":[],"apidae-territoires":[420,429,423,435,1730,414,417,432,441,438],"apidae-salles_equipees_pour":[],"apidae-salles_equipement":[],"apidae-salles_hebergement":[],"apidae-salles_restauration":[],"apidae-categories":[],"apidae-specialites":[],"apidae-indications_periode":[405,411,408,615],"apidae-types_label":[],"apidae-hotel_classement":[],"apidae-types_hebergement":[],"apidae-tourisme_affaire":[1719],"class_list":["post-17767","apidae","type-apidae","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bar-Restaurant Le Rod\u00e9o - Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/fiche\/bar-restaurant-le-rodeo-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bar-Restaurant Le Rod\u00e9o - Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/fiche\/bar-restaurant-le-rodeo-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/en\\\/fiche\\\/bar-restaurant-le-rodeo-2\\\/\",\"url\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/en\\\/fiche\\\/bar-restaurant-le-rodeo-2\\\/\",\"name\":\"Bar-Restaurant Le Rod\u00e9o - Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/en\\\/#website\"},\"datePublished\":\"2026-06-03T08:26:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/en\\\/fiche\\\/bar-restaurant-le-rodeo-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/en\\\/fiche\\\/bar-restaurant-le-rodeo-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/en\\\/fiche\\\/bar-restaurant-le-rodeo-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/en\\\/a-stones-throw-from-burgundy-a-welcoming-countryside-between-bresse-and-saone\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bar-Restaurant Le Rod\u00e9o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/en\\\/\",\"name\":\"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/en\\\/#organization\",\"name\":\"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux\",\"url\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-pays-de-bage-and-pont-de-vaux.svg\",\"contentUrl\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-pays-de-bage-and-pont-de-vaux.svg\",\"caption\":\"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bage-pontdevaux-tourisme.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bar-Restaurant Le Rod\u00e9o - Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/fiche\/bar-restaurant-le-rodeo-2\/","og_locale":"en_US","og_type":"article","og_title":"Bar-Restaurant Le Rod\u00e9o - Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux","og_url":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/fiche\/bar-restaurant-le-rodeo-2\/","og_site_name":"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/fiche\/bar-restaurant-le-rodeo-2\/","url":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/fiche\/bar-restaurant-le-rodeo-2\/","name":"Bar-Restaurant Le Rod\u00e9o - Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux","isPartOf":{"@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/#website"},"datePublished":"2026-06-03T08:26:33+00:00","breadcrumb":{"@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/fiche\/bar-restaurant-le-rodeo-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bage-pontdevaux-tourisme.com\/en\/fiche\/bar-restaurant-le-rodeo-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/fiche\/bar-restaurant-le-rodeo-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/a-stones-throw-from-burgundy-a-welcoming-countryside-between-bresse-and-saone\/"},{"@type":"ListItem","position":2,"name":"Bar-Restaurant Le Rod\u00e9o"}]},{"@type":"WebSite","@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/#website","url":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/","name":"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux","description":"","publisher":{"@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/#organization","name":"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux","url":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/05\/logo-pays-de-bage-and-pont-de-vaux.svg","contentUrl":"https:\/\/www.bage-pontdevaux-tourisme.com\/wp-content\/uploads\/2025\/05\/logo-pays-de-bage-and-pont-de-vaux.svg","caption":"Office de Tourisme du Pays de Bag\u00e9 et de Pont de Vaux"},"image":{"@id":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae\/17767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae"}],"about":[{"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/types\/apidae"}],"wp:attachment":[{"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/media?parent=17767"}],"wp:term":[{"taxonomy":"apidae-selections","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-selections?post=17767"},{"taxonomy":"apidae-environnements","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-environnements?post=17767"},{"taxonomy":"apidae-chaines","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-chaines?post=17767"},{"taxonomy":"apidae-communes","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-communes?post=17767"},{"taxonomy":"apidae-modes_paiement","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-modes_paiement?post=17767"},{"taxonomy":"apidae-services","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-services?post=17767"},{"taxonomy":"apidae-langues_parlees","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-langues_parlees?post=17767"},{"taxonomy":"apidae-equipements","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-equipements?post=17767"},{"taxonomy":"apidae-conforts","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-conforts?post=17767"},{"taxonomy":"apidae-activites","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-activites?post=17767"},{"taxonomy":"apidae-tourismes_adaptes","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-tourismes_adaptes?post=17767"},{"taxonomy":"apidae-typologies_promo_sitra","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-typologies_promo_sitra?post=17767"},{"taxonomy":"apidae-types_clientele","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-types_clientele?post=17767"},{"taxonomy":"apidae-types_patrimoine_culturel","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-types_patrimoine_culturel?post=17767"},{"taxonomy":"apidae-types_commerce_service","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-types_commerce_service?post=17767"},{"taxonomy":"apidae-activites_sportives","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-activites_sportives?post=17767"},{"taxonomy":"apidae-commerce_type_detaille","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-commerce_type_detaille?post=17767"},{"taxonomy":"apidae-fete_manifestation_cat","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-fete_manifestation_cat?post=17767"},{"taxonomy":"apidae-criteres_internes","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-criteres_internes?post=17767"},{"taxonomy":"apidae-territoires","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-territoires?post=17767"},{"taxonomy":"apidae-salles_equipees_pour","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-salles_equipees_pour?post=17767"},{"taxonomy":"apidae-salles_equipement","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-salles_equipement?post=17767"},{"taxonomy":"apidae-salles_hebergement","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-salles_hebergement?post=17767"},{"taxonomy":"apidae-salles_restauration","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-salles_restauration?post=17767"},{"taxonomy":"apidae-categories","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-categories?post=17767"},{"taxonomy":"apidae-specialites","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-specialites?post=17767"},{"taxonomy":"apidae-indications_periode","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-indications_periode?post=17767"},{"taxonomy":"apidae-types_label","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-types_label?post=17767"},{"taxonomy":"apidae-hotel_classement","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-hotel_classement?post=17767"},{"taxonomy":"apidae-types_hebergement","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-types_hebergement?post=17767"},{"taxonomy":"apidae-tourisme_affaire","embeddable":true,"href":"https:\/\/www.bage-pontdevaux-tourisme.com\/en\/wp-json\/wp\/v2\/apidae-tourisme_affaire?post=17767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}